{"id":6727,"date":"2024-05-09T19:09:39","date_gmt":"2024-05-09T19:09:39","guid":{"rendered":"https:\/\/accademia-italiana.it\/information-generales\/"},"modified":"2024-06-25T08:19:41","modified_gmt":"2024-06-25T08:19:41","slug":"informaciones-generales","status":"publish","type":"page","link":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/","title":{"rendered":"Informaci\u00f3n general"},"content":{"rendered":"<style>.kb-row-layout-id6727_d7c041-a1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6727_d7c041-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6727_d7c041-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id6727_d7c041-a1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6727_d7c041-a1 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6727_d7c041-a1 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6727_d7c041-a1 alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col,.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6727_3f4ea9-d9{position:relative;}@media all and (max-width: 1024px){.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6727_3f4ea9-d9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6727_3f4ea9-d9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6727_6310cc-d6, .wp-block-kadence-advancedheading.kt-adv-heading6727_6310cc-d6[data-kb-block=\"kb-adv-heading6727_6310cc-d6\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6727_6310cc-d6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_6310cc-d6[data-kb-block=\"kb-adv-heading6727_6310cc-d6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_6310cc-d6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_6310cc-d6[data-kb-block=\"kb-adv-heading6727_6310cc-d6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6727_6310cc-d6 wp-block-kadence-advancedheading has-theme-palette-6-color has-text-color\" data-kb-block=\"kb-adv-heading6727_6310cc-d6\">Todos los cursos desarrollan habilidades comunicativas pr\u00e1cticas. Los estudiantes pueden aprender y practicar italiano en clases estructuradas e imaginativas que incluyen gram\u00e1tica, vocabulario y conversaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-theme-palette-6-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\">Todos nuestros cursos est\u00e1n reconocidos por la Universidad para Extranjeros de Siena. El curso de italiano tambi\u00e9n incluye muchas actividades sociales y culturales.<\/p>\n\n\n\n<p class=\"has-theme-palette-6-color has-text-color has-link-color wp-elements-2 wp-block-paragraph\">El programa social de la escuela ofrece m\u00e1s oportunidades de practicar el italiano mientras se conoce a otros estudiantes y profesores.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column6727_ec27a4-21 > .kt-inside-inner-col,.kadence-column6727_ec27a4-21 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6727_ec27a4-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6727_ec27a4-21 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6727_ec27a4-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6727_ec27a4-21 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6727_ec27a4-21{position:relative;}@media all and (max-width: 1024px){.kadence-column6727_ec27a4-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6727_ec27a4-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6727_ec27a4-21\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6727_615749-a8, .wp-block-kadence-advancedheading.kt-adv-heading6727_615749-a8[data-kb-block=\"kb-adv-heading6727_615749-a8\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6727_615749-a8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_615749-a8[data-kb-block=\"kb-adv-heading6727_615749-a8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_615749-a8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_615749-a8[data-kb-block=\"kb-adv-heading6727_615749-a8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6727_615749-a8 wp-block-kadence-advancedheading has-theme-palette-6-color has-text-color\" data-kb-block=\"kb-adv-heading6727_615749-a8\">Las clases est\u00e1n formadas por un m\u00ednimo de 4 y un m\u00e1ximo de 10 alumnos, lo que crea un ambiente agradable y positivo en el que el profesor puede evaluar el progreso ling\u00fc\u00edstico de cada estudiante.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6727_813a26-4e, .wp-block-kadence-advancedheading.kt-adv-heading6727_813a26-4e[data-kb-block=\"kb-adv-heading6727_813a26-4e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6727_813a26-4e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_813a26-4e[data-kb-block=\"kb-adv-heading6727_813a26-4e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_813a26-4e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_813a26-4e[data-kb-block=\"kb-adv-heading6727_813a26-4e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6727_813a26-4e wp-block-kadence-advancedheading has-theme-palette-6-color has-text-color\" data-kb-block=\"kb-adv-heading6727_813a26-4e\">Los participantes son asignados a las clases de lengua seg\u00fan su nivel inicial de italiano y su nacionalidad. En todas las clases hay una buena mezcla de nacionalidades, por lo que se anima a los estudiantes a utilizar el italiano como lengua oficial. Nuestros profesores, altamente cualificados, eval\u00faan el progreso de los estudiantes mediante un examen semanal y tareas para casa.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id6727_a5963a-de > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6727_a5963a-de > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6727_a5963a-de > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6727_a5963a-de > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6727_a5963a-de > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6727_a5963a-de > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6727_a5963a-de alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6727_737944-af > .kt-inside-inner-col{display:flex;}.kadence-column6727_737944-af > .kt-inside-inner-col,.kadence-column6727_737944-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6727_737944-af > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6727_737944-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column6727_737944-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6727_737944-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6727_737944-af{position:relative;}@media all and (max-width: 1024px){.kadence-column6727_737944-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6727_737944-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6727_737944-af\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6727_f62e2a-0d, .wp-block-kadence-advancedheading.kt-adv-heading6727_f62e2a-0d[data-kb-block=\"kb-adv-heading6727_f62e2a-0d\"]{padding-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6727_f62e2a-0d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_f62e2a-0d[data-kb-block=\"kb-adv-heading6727_f62e2a-0d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_f62e2a-0d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_f62e2a-0d[data-kb-block=\"kb-adv-heading6727_f62e2a-0d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading6727_f62e2a-0d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6727_f62e2a-0d\">Prueba de evaluaci\u00f3n :<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49, .wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49[data-kb-block=\"kb-adv-heading6727_307cb2-49\"]{padding-bottom:var(--global-kb-spacing-lg, 3rem);margin-bottom:0px;font-style:normal;border-bottom:1px solid var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49[data-kb-block=\"kb-adv-heading6727_307cb2-49\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49[data-kb-block=\"kb-adv-heading6727_307cb2-49\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49, .wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49[data-kb-block=\"kb-adv-heading6727_307cb2-49\"]{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49, .wp-block-kadence-advancedheading.kt-adv-heading6727_307cb2-49[data-kb-block=\"kb-adv-heading6727_307cb2-49\"]{border-bottom:1px solid var(--global-palette3, #1A202C);}}<\/style>\n<p class=\"kt-adv-heading6727_307cb2-49 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6727_307cb2-49\">El primer d\u00eda del curso, a las 8.30 horas, los estudiantes no principiantes realizan una prueba de acceso escrita y oral para evaluar sus capacidades y decidir en qu\u00e9 grupo de estudio se les asignar\u00e1.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6727_7503d8-6d, .wp-block-kadence-advancedheading.kt-adv-heading6727_7503d8-6d[data-kb-block=\"kb-adv-heading6727_7503d8-6d\"]{padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-top:var(--global-kb-spacing-lg, 3rem);margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6727_7503d8-6d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_7503d8-6d[data-kb-block=\"kb-adv-heading6727_7503d8-6d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_7503d8-6d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_7503d8-6d[data-kb-block=\"kb-adv-heading6727_7503d8-6d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading6727_7503d8-6d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6727_7503d8-6d\">Certificados<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a, .wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a[data-kb-block=\"kb-adv-heading6727_64b8ae-1a\"]{padding-bottom:var(--global-kb-spacing-lg, 3rem);margin-bottom:0px;font-style:normal;border-bottom:1px solid var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a[data-kb-block=\"kb-adv-heading6727_64b8ae-1a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a[data-kb-block=\"kb-adv-heading6727_64b8ae-1a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a, .wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a[data-kb-block=\"kb-adv-heading6727_64b8ae-1a\"]{border-bottom:1px solid var(--global-palette3, #1A202C);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a, .wp-block-kadence-advancedheading.kt-adv-heading6727_64b8ae-1a[data-kb-block=\"kb-adv-heading6727_64b8ae-1a\"]{border-bottom:1px solid var(--global-palette3, #1A202C);}}<\/style>\n<p class=\"kt-adv-heading6727_64b8ae-1a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6727_64b8ae-1a\">Al final de cada curso, los estudiantes reciben un certificado en el que se indica la duraci\u00f3n del curso y el nivel de lengua alcanzado. Al final del sexto nivel, los estudiantes reciben un diploma especial de la \u00abAccademia Italiana\u00bb.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6727_77eb19-3c, .wp-block-kadence-advancedheading.kt-adv-heading6727_77eb19-3c[data-kb-block=\"kb-adv-heading6727_77eb19-3c\"]{padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-top:var(--global-kb-spacing-lg, 3rem);margin-bottom:0px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6727_77eb19-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6727_77eb19-3c[data-kb-block=\"kb-adv-heading6727_77eb19-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6727_77eb19-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6727_77eb19-3c[data-kb-block=\"kb-adv-heading6727_77eb19-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading6727_77eb19-3c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6727_77eb19-3c\">Niveles<\/h2>\n\n\n\n<figure class=\"wp-block-table th-dred td-dred border-dred\"><table><thead><tr><th>Niveles<br>Academia de italiano<\/th><th>Niveles comunes<br>Marco europeo<\/th><\/tr><\/thead><tbody><tr><td>Nivel 1 Principiante<\/td><td>Nivel 1 Principiante<br>A1 Perc\u00e9e<\/td><\/tr><tr><td>Nivel 2 &#8211; Elemental<\/td><td>A1<\/td><\/tr><tr><td>Nivel 3 &#8211; Preintermedio<\/td><td>A2<\/td><\/tr><tr><td>Nivel 4 &#8211; Intermedio<\/td><td>B1<\/td><\/tr><tr><td>Nivel 5 &#8211; Intermedio alto<\/td><td>B2<\/td><\/tr><tr><td>Nivel 6 &#8211; Avanzado<\/td><td>C1<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Todos los cursos desarrollan habilidades comunicativas pr\u00e1cticas. Los estudiantes pueden aprender y practicar italiano en clases estructuradas e imaginativas que incluyen gram\u00e1tica, vocabulario y conversaci\u00f3n. Todos nuestros cursos est\u00e1n reconocidos por la Universidad para Extranjeros de Siena. El curso de italiano tambi\u00e9n incluye muchas actividades sociales y culturales. El programa social de la escuela ofrece&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12162,"parent":6547,"menu_order":173,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"school":[],"class_list":["post-6727","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informaci\u00f3n General sobre Cursos de Italiano en Italia | Accademia Italiana<\/title>\n<meta name=\"description\" content=\"Accede a informaci\u00f3n general sobre los cursos de italiano en Accademia Italiana en Salerno y N\u00e1poles. Descubre los niveles de los cursos, los horarios y las certificaciones disponibles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informaci\u00f3n General sobre Cursos de Italiano en Italia | Accademia Italiana\" \/>\n<meta property=\"og:description\" content=\"Accede a informaci\u00f3n general sobre los cursos de italiano en Accademia Italiana en Salerno y N\u00e1poles. Descubre los niveles de los cursos, los horarios y las certificaciones disponibles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/\" \/>\n<meta property=\"og:site_name\" content=\"Accademia Italiana\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-25T08:19:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/05\/AIS-team.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"717\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/\",\"url\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/\",\"name\":\"Informaci\u00f3n General sobre Cursos de Italiano en Italia | Accademia Italiana\",\"isPartOf\":{\"@id\":\"https:\/\/accademia-italiana.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg\",\"datePublished\":\"2024-05-09T19:09:39+00:00\",\"dateModified\":\"2024-06-25T08:19:41+00:00\",\"description\":\"Accede a informaci\u00f3n general sobre los cursos de italiano en Accademia Italiana en Salerno y N\u00e1poles. Descubre los niveles de los cursos, los horarios y las certificaciones disponibles.\",\"breadcrumb\":{\"@id\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#primaryimage\",\"url\":\"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg\",\"contentUrl\":\"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg\",\"width\":1000,\"height\":696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/accademia-italiana.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso\",\"item\":\"https:\/\/accademia-italiana.it\/es\/curso\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informaci\u00f3n general\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/accademia-italiana.it\/es\/#website\",\"url\":\"https:\/\/accademia-italiana.it\/es\/\",\"name\":\"Accademia Italiana\",\"description\":\"Italian Language School in Italy\",\"publisher\":{\"@id\":\"https:\/\/accademia-italiana.it\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/accademia-italiana.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/accademia-italiana.it\/es\/#organization\",\"name\":\"Italian Language School in Italy, italian language school, italian language courses, language school Italyee\",\"url\":\"https:\/\/accademia-italiana.it\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/accademia-italiana.it\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/04\/logo-accademia-semplice-01-Photoroom.png-Photoroom.svg\",\"contentUrl\":\"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/04\/logo-accademia-semplice-01-Photoroom.png-Photoroom.svg\",\"caption\":\"Italian Language School in Italy, italian language school, italian language courses, language school Italyee\"},\"image\":{\"@id\":\"https:\/\/accademia-italiana.it\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informaci\u00f3n General sobre Cursos de Italiano en Italia | Accademia Italiana","description":"Accede a informaci\u00f3n general sobre los cursos de italiano en Accademia Italiana en Salerno y N\u00e1poles. Descubre los niveles de los cursos, los horarios y las certificaciones disponibles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/","og_locale":"es_ES","og_type":"article","og_title":"Informaci\u00f3n General sobre Cursos de Italiano en Italia | Accademia Italiana","og_description":"Accede a informaci\u00f3n general sobre los cursos de italiano en Accademia Italiana en Salerno y N\u00e1poles. Descubre los niveles de los cursos, los horarios y las certificaciones disponibles.","og_url":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/","og_site_name":"Accademia Italiana","article_modified_time":"2024-06-25T08:19:41+00:00","og_image":[{"width":717,"height":560,"url":"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/05\/AIS-team.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/","url":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/","name":"Informaci\u00f3n General sobre Cursos de Italiano en Italia | Accademia Italiana","isPartOf":{"@id":"https:\/\/accademia-italiana.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#primaryimage"},"image":{"@id":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#primaryimage"},"thumbnailUrl":"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg","datePublished":"2024-05-09T19:09:39+00:00","dateModified":"2024-06-25T08:19:41+00:00","description":"Accede a informaci\u00f3n general sobre los cursos de italiano en Accademia Italiana en Salerno y N\u00e1poles. Descubre los niveles de los cursos, los horarios y las certificaciones disponibles.","breadcrumb":{"@id":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/accademia-italiana.it\/es\/informaciones-generales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#primaryimage","url":"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg","contentUrl":"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg","width":1000,"height":696},{"@type":"BreadcrumbList","@id":"https:\/\/accademia-italiana.it\/es\/informaciones-generales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/accademia-italiana.it\/es\/"},{"@type":"ListItem","position":2,"name":"Curso","item":"https:\/\/accademia-italiana.it\/es\/curso\/"},{"@type":"ListItem","position":3,"name":"Informaci\u00f3n general"}]},{"@type":"WebSite","@id":"https:\/\/accademia-italiana.it\/es\/#website","url":"https:\/\/accademia-italiana.it\/es\/","name":"Accademia Italiana","description":"Italian Language School in Italy","publisher":{"@id":"https:\/\/accademia-italiana.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/accademia-italiana.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/accademia-italiana.it\/es\/#organization","name":"Italian Language School in Italy, italian language school, italian language courses, language school Italyee","url":"https:\/\/accademia-italiana.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/accademia-italiana.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/04\/logo-accademia-semplice-01-Photoroom.png-Photoroom.svg","contentUrl":"https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/04\/logo-accademia-semplice-01-Photoroom.png-Photoroom.svg","caption":"Italian Language School in Italy, italian language school, italian language courses, language school Italyee"},"image":{"@id":"https:\/\/accademia-italiana.it\/es\/#\/schema\/logo\/image\/"}}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/accademia-italiana.it\/wp-content\/uploads\/2024\/10\/accademia-italiana-general-courses-1.jpg",1000,696,false],"author_info":{"display_name":"admin","author_link":"https:\/\/accademia-italiana.it\/es\/author\/hemadmin\/"},"comment_info":"","_links":{"self":[{"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/pages\/6727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/comments?post=6727"}],"version-history":[{"count":0,"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/pages\/6727\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/pages\/6547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/media\/12162"}],"wp:attachment":[{"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/media?parent=6727"}],"wp:term":[{"taxonomy":"school","embeddable":true,"href":"https:\/\/accademia-italiana.it\/es\/wp-json\/wp\/v2\/school?post=6727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}